{"id":376,"count":8,"description":"In dieser Kategorie findest du Beitr\u00e4ge zum Thema Chancengleichheit und gesellschaftlicher Teilhabe. Daf\u00fcr vermitteln wir Hintergr\u00fcnde und zeigen, wie du mit einem Ehrenamt Chancen verbessern und Menschen in ihrer Entwicklung st\u00e4rken kannst.","link":"https:\/\/vostel.de\/blog\/tag\/chancengleichheit\/","name":"Chancengleichheit","slug":"chancengleichheit","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Chancengleichheit | vostel.de<\/title>\n<meta name=\"description\" content=\"Entdecke Beitr\u00e4ge zu Chancengleichheit und erfahre, wie ein Ehrenamt soziale Barrieren abbaut und gerechtere Teilhabe erm\u00f6glicht.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vostel.de\/blog\/tag\/chancengleichheit\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chancengleichheit Archive\" \/>\n<meta property=\"og:description\" content=\"Entdecke Beitr\u00e4ge zu Chancengleichheit und erfahre, wie ein Ehrenamt soziale Barrieren abbaut und gerechtere Teilhabe erm\u00f6glicht.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vostel.de\/blog\/tag\/chancengleichheit\/\" \/>\n<meta property=\"og:site_name\" content=\"vostel.de Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/vostel.de\\\/blog\\\/tag\\\/chancengleichheit\\\/\",\"url\":\"https:\\\/\\\/vostel.de\\\/blog\\\/tag\\\/chancengleichheit\\\/\",\"name\":\"Chancengleichheit | vostel.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vostel.de\\\/blog\\\/#website\"},\"description\":\"Entdecke Beitr\u00e4ge zu Chancengleichheit und erfahre, wie ein Ehrenamt soziale Barrieren abbaut und gerechtere Teilhabe erm\u00f6glicht.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vostel.de\\\/blog\\\/tag\\\/chancengleichheit\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vostel.de\\\/blog\\\/tag\\\/chancengleichheit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/vostel.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chancengleichheit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vostel.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/vostel.de\\\/blog\\\/\",\"name\":\"vostel.de Blog\",\"description\":\"Inspirationen f\u00fcr eine bessere und nachhaltigere Zukunft\",\"publisher\":{\"@id\":\"https:\\\/\\\/vostel.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vostel.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vostel.de\\\/blog\\\/#organization\",\"name\":\"vostel.de Blog\",\"url\":\"https:\\\/\\\/vostel.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/vostel.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vostel.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-de-rot-large.png\",\"contentUrl\":\"https:\\\/\\\/vostel.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-de-rot-large.png\",\"width\":1801,\"height\":589,\"caption\":\"vostel.de Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/vostel.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Chancengleichheit | vostel.de","description":"Entdecke Beitr\u00e4ge zu Chancengleichheit und erfahre, wie ein Ehrenamt soziale Barrieren abbaut und gerechtere Teilhabe erm\u00f6glicht.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vostel.de\/blog\/tag\/chancengleichheit\/","og_locale":"de_DE","og_type":"article","og_title":"Chancengleichheit Archive","og_description":"Entdecke Beitr\u00e4ge zu Chancengleichheit und erfahre, wie ein Ehrenamt soziale Barrieren abbaut und gerechtere Teilhabe erm\u00f6glicht.","og_url":"https:\/\/vostel.de\/blog\/tag\/chancengleichheit\/","og_site_name":"vostel.de Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/vostel.de\/blog\/tag\/chancengleichheit\/","url":"https:\/\/vostel.de\/blog\/tag\/chancengleichheit\/","name":"Chancengleichheit | vostel.de","isPartOf":{"@id":"https:\/\/vostel.de\/blog\/#website"},"description":"Entdecke Beitr\u00e4ge zu Chancengleichheit und erfahre, wie ein Ehrenamt soziale Barrieren abbaut und gerechtere Teilhabe erm\u00f6glicht.","breadcrumb":{"@id":"https:\/\/vostel.de\/blog\/tag\/chancengleichheit\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/vostel.de\/blog\/tag\/chancengleichheit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/vostel.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Chancengleichheit"}]},{"@type":"WebSite","@id":"https:\/\/vostel.de\/blog\/#website","url":"https:\/\/vostel.de\/blog\/","name":"vostel.de Blog","description":"Inspirationen f\u00fcr eine bessere und nachhaltigere Zukunft","publisher":{"@id":"https:\/\/vostel.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vostel.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/vostel.de\/blog\/#organization","name":"vostel.de Blog","url":"https:\/\/vostel.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/vostel.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/vostel.de\/blog\/wp-content\/uploads\/2024\/03\/logo-de-rot-large.png","contentUrl":"https:\/\/vostel.de\/blog\/wp-content\/uploads\/2024\/03\/logo-de-rot-large.png","width":1801,"height":589,"caption":"vostel.de Blog"},"image":{"@id":"https:\/\/vostel.de\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/vostel.de\/blog\/wp-json\/wp\/v2\/tags\/376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vostel.de\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/vostel.de\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/vostel.de\/blog\/wp-json\/wp\/v2\/posts?tags=376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}